{"id":44644,"date":"2024-10-09T09:21:34","date_gmt":"2024-10-09T09:21:34","guid":{"rendered":"http:\/\/uvt.ro\/cercetare\/?post_type=evenimente&#038;p=44644"},"modified":"2025-01-30T10:27:44","modified_gmt":"2025-01-30T10:27:44","slug":"ecreb-research-seminar-research-as-a-career-choice-invited-speaker-vladimir-andric-phd-research-associate-institute-of-economic-sciences-ies-belgrade-serbia","status":"publish","type":"evenimente","link":"https:\/\/uvt.ro\/cercetare\/evenimente-stiinti\/ecreb-research-seminar-research-as-a-career-choice-invited-speaker-vladimir-andric-phd-research-associate-institute-of-economic-sciences-ies-belgrade-serbia\/","title":{"rendered":"ECREB Research Seminar &#8211; RESEARCH AS A CAREER CHOICE (Invited Speaker: Vladimir Andric, PhD, Research Associate, Institute of Economic Sciences (IES), Belgrade, Serbia)"},"content":{"rendered":"","protected":false},"author":55,"template":"","meta":{"_members_access_role":[],"_members_access_error":"","_links_to":"","_links_to_target":""},"anvergura":[],"facultate":[],"class_list":["post-44644","evenimente","type-evenimente","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/uvt.ro\/cercetare\/wp-json\/wp\/v2\/evenimente\/44644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uvt.ro\/cercetare\/wp-json\/wp\/v2\/evenimente"}],"about":[{"href":"https:\/\/uvt.ro\/cercetare\/wp-json\/wp\/v2\/types\/evenimente"}],"author":[{"embeddable":true,"href":"https:\/\/uvt.ro\/cercetare\/wp-json\/wp\/v2\/users\/55"}],"wp:attachment":[{"href":"https:\/\/uvt.ro\/cercetare\/wp-json\/wp\/v2\/media?parent=44644"}],"wp:term":[{"taxonomy":"anvergura","embeddable":true,"href":"https:\/\/uvt.ro\/cercetare\/wp-json\/wp\/v2\/anvergura?post=44644"},{"taxonomy":"facultate","embeddable":true,"href":"https:\/\/uvt.ro\/cercetare\/wp-json\/wp\/v2\/facultate?post=44644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}